{"id":85,"date":"2023-03-09T12:53:47","date_gmt":"2023-03-09T12:53:47","guid":{"rendered":"https:\/\/tecnologia.vamtam.com\/?page_id=85"},"modified":"2025-08-12T14:16:24","modified_gmt":"2025-08-12T14:16:24","slug":"about","status":"publish","type":"page","link":"https:\/\/hitech.al\/de\/about\/","title":{"rendered":"Um"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"85\" class=\"elementor elementor-85\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8802642 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8802642\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-da9293b\" data-id=\"da9293b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0f1c76b animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"0f1c76b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Der Bereitstellung von Spitzenleistungen verpflichtet<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0f6ac8 animated-slow elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d0f6ac8\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;,&quot;_animation_tablet&quot;:&quot;none&quot;,&quot;_animation_delay&quot;:300}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p class=\"elementor-heading-title elementor-size-default\">Jeder hat eine Geschichte. Hier ist unsere.<\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e735dc0 elementor-widget elementor-widget-spacer\" data-id=\"e735dc0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-de2806a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"de2806a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-858f2b0\" data-id=\"858f2b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c6a7cd elementor-view-default elementor-invisible elementor-widget elementor-widget-icon\" data-id=\"9c6a7cd\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;sticky&quot;:&quot;top&quot;,&quot;sticky_offset&quot;:200,&quot;sticky_parent&quot;:&quot;yes&quot;,&quot;motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;motion_fx_scale_effect&quot;:&quot;yes&quot;,&quot;motion_fx_scale_direction&quot;:&quot;out-in-out&quot;,&quot;motion_fx_scale_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:8,&quot;sizes&quot;:[]},&quot;motion_fx_scale_range&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:15,&quot;end&quot;:50}},&quot;motion_fx_devices&quot;:[&quot;desktop&quot;,&quot;tablet&quot;],&quot;_animation&quot;:&quot;zoomIn&quot;,&quot;_animation_delay&quot;:200,&quot;_animation_mobile&quot;:&quot;none&quot;,&quot;sticky_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;,&quot;mobile&quot;],&quot;sticky_effects_offset&quot;:0,&quot;sticky_anchor_link_offset&quot;:0}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-741b698 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"741b698\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8931f7e\" data-id=\"8931f7e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e97807e elementor-widget elementor-widget-image\" data-id=\"e97807e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"566\" height=\"428\" src=\"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg\" class=\"attachment-large size-large wp-image-4129\" alt=\"\" srcset=\"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg 566w, https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash-300x227.jpg 300w\" sizes=\"(max-width: 566px) 100vw, 566px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9bc1642\" data-id=\"9bc1642\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12e7d31 elementor-widget__width-auto elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"12e7d31\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e212345 elementor-widget elementor-widget-heading\" data-id=\"e212345\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Der Anfang<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3a52daa elementor-widget elementor-widget-text-editor\" data-id=\"3a52daa\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUnsere Reise begann 2013, als unser CEO Mandi Blaceri mit dem Aufbau einer E-Commerce-Website f\u00fcr sein Familienunternehmen begann. Dies f\u00fchrte dazu, dass er sich intensiv mit der Web- und IT-Branche im Allgemeinen besch\u00e4ftigte.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-72e9117 elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72e9117\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-666b6a6\" data-id=\"666b6a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-849194c elementor-widget elementor-widget-heading\" data-id=\"849194c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Mission<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1cc31e7 elementor-widget elementor-widget-text-editor\" data-id=\"1cc31e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei HiTech Media haben wir es uns zur Aufgabe gemacht, den pers\u00f6nlichen Service lokaler IT-Anbieter mit der Leistungsf\u00e4higkeit eines nationalen Netzwerks zu verbinden. Wir glauben, das ist einfacher als es klingt. Unsere Niederlassungen bieten hochkar\u00e4tige IT-Services, die unsere Kunden sch\u00e4tzen, und zwar durch erfahrene Mitarbeiter vor Ort.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d201a1\" data-id=\"0d201a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1c3000 elementor-widget__width-auto elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b1c3000\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b065953 elementor-widget elementor-widget-image\" data-id=\"b065953\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"566\" height=\"508\" src=\"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/austin-distel-wD1LRb9OeEo-unsplash.jpg\" class=\"attachment-large size-large wp-image-4136\" alt=\"\" srcset=\"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/austin-distel-wD1LRb9OeEo-unsplash.jpg 566w, https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/austin-distel-wD1LRb9OeEo-unsplash-300x269.jpg 300w\" sizes=\"(max-width: 566px) 100vw, 566px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-08422ce elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"08422ce\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-aef0697\" data-id=\"aef0697\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5d42005 elementor-widget elementor-widget-image\" data-id=\"5d42005\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"566\" height=\"428\" src=\"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/desola-lanre-ologun-IgUR1iX0mqM-unsplash.jpg\" class=\"attachment-large size-large wp-image-4137\" alt=\"\" srcset=\"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/desola-lanre-ologun-IgUR1iX0mqM-unsplash.jpg 566w, https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/desola-lanre-ologun-IgUR1iX0mqM-unsplash-300x227.jpg 300w\" sizes=\"(max-width: 566px) 100vw, 566px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-549455a\" data-id=\"549455a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b3cdf26 elementor-widget__width-auto elementor-absolute elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b3cdf26\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<i aria-hidden=\"true\" class=\"far fa-dot-circle\"><\/i>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-206d869 elementor-widget elementor-widget-heading\" data-id=\"206d869\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Wir sind global<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f5f399e elementor-widget elementor-widget-text-editor\" data-id=\"f5f399e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tUnser nationales Netzwerk erm\u00f6glicht es uns, erstklassige Dienste wie dedizierte vCIOs, spezialisierte Sicherheits- und Compliance-Beratungsdienste, einen rund um die Uhr verf\u00fcgbaren Helpdesk und mehr anzubieten.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-af573f4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"af573f4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ff2aef\" data-id=\"1ff2aef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bf32b31 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"bf32b31\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Warum wir<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-868305d elementor-widget elementor-widget-text-editor\" data-id=\"868305d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir wissen, dass es im Gesch\u00e4ftsleben chaotisch zugehen kann. Genau da kommen wir ins Spiel. Wir konzentrieren uns darauf, f\u00fcr die n\u00f6tige Balance zu sorgen. Dies erreichen wir durch echte Partnerschaften mit unseren Kunden. Bei uns arbeiten Sie mit einem Team zusammen, das Ihre Probleme und Ziele versteht. Wir helfen Ihnen, Ordnung ins Chaos zu bringen.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-4658564 vamtam-has-underline-anim elementor-widget elementor-widget-button\" data-id=\"4658564\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hitech.al\/de\/why-us\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mehr erfahren<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-359b217 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"359b217\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f53713d\" data-id=\"f53713d\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-812e690 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"812e690\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_motion_fx_devices&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-ed81ef2\" data-id=\"ed81ef2\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;background_motion_fx_motion_fx_scrolling&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_effect&quot;:&quot;yes&quot;,&quot;background_motion_fx_translateY_speed&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:3,&quot;sizes&quot;:[]},&quot;background_motion_fx_devices&quot;:[&quot;desktop&quot;],&quot;background_motion_fx_translateY_affectedRange&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:{&quot;start&quot;:0,&quot;end&quot;:100}}}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee8f3b8 elementor-widget__width-auto elementor-widget elementor-widget-heading\" data-id=\"ee8f3b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Unsere Grundwerte<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df4d622 elementor-widget elementor-widget-spacer\" data-id=\"df4d622\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25318f3 elementor-widget elementor-widget-heading\" data-id=\"25318f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unsere Kultur basiert auf f\u00fcnf Schl\u00fcsselattributen, die uns von der Konkurrenz unterscheiden.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14bd584 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14bd584\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-af55ee9 elementor-invisible\" data-id=\"af55ee9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;,&quot;animation_delay&quot;:200}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-6c3b59f elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"6c3b59f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-Target\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tLeidenschaftlich\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir sind mit gro\u00dfer Begeisterung dabei, ein erstklassiges Erlebnis zu bieten.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-efafb3b elementor-invisible\" data-id=\"efafb3b\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;,&quot;animation_delay&quot;:400}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-7e3badf elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"7e3badf\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-Respectful\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRespektvoll\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir sind h\u00f6flich und freundlich zueinander, auch wenn es mal schwierig wird.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-6be46f9 elementor-invisible\" data-id=\"6be46f9\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;,&quot;animation_delay&quot;:600}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-f1507c3 elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"f1507c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-Ownership\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEigentum\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir sind befugt, unsere Arbeit zu erledigen und auf ein gemeinsames Ziel hinzuarbeiten.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-7997df1 elementor-invisible\" data-id=\"7997df1\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;,&quot;animation_tablet&quot;:&quot;none&quot;,&quot;animation_delay&quot;:800}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-586ae6c elementor-view-default elementor-position-block-start elementor-mobile-position-block-start elementor-widget elementor-widget-icon-box\" data-id=\"586ae6c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\t\t\t<div class=\"elementor-icon-box-icon\">\n\t\t\t\t<span  class=\"elementor-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"vamtamtheme- vamtam-theme-Unified\"><\/i>\t\t\t\t<\/span>\n\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h4 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tEinheitlich\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h4>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tWir arbeiten als Team und vertrauen einander, um ein nahtloses Erlebnis zu schaffen.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1aace99 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1aace99\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-06fcd3c\" data-id=\"06fcd3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-99433d4 elementor-widget elementor-widget-spacer\" data-id=\"99433d4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d8cbd3b elementor-widget elementor-widget-heading\" data-id=\"d8cbd3b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ein Team, das auf Erfahrung aufbaut<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b485696 elementor-widget elementor-widget-text-editor\" data-id=\"b485696\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir bauen unser Netzwerk landesweit weiter aus und stellen ein dynamisches Team mit erstklassigem Service und technischen F\u00e4higkeiten zusammen. Unser Team w\u00e4chst schnell.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42aef8e elementor-widget elementor-widget-spacer\" data-id=\"42aef8e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c225281 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c225281\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8c39862\" data-id=\"8c39862\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1a859ea elementor-widget elementor-widget-image-carousel\" data-id=\"1a859ea\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;5&quot;,&quot;slides_to_show_tablet&quot;:&quot;4&quot;,&quot;slides_to_show_mobile&quot;:&quot;3&quot;,&quot;slides_to_scroll_mobile&quot;:&quot;3&quot;,&quot;navigation&quot;:&quot;none&quot;,&quot;lazyload&quot;:&quot;yes&quot;,&quot;image_spacing_custom&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:150,&quot;sizes&quot;:[]},&quot;image_spacing_custom_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:40,&quot;sizes&quot;:[]},&quot;image_spacing_custom_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;autoplay_speed&quot;:1900,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image-carousel-wrapper swiper\" role=\"region\" aria-roledescription=\"carousel\" aria-label=\"Bilderkarussell\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\" aria-live=\"off\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"1 von 5\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/hitech.al\/wp-content\/uploads\/elementor\/thumbs\/google@2x-r9rmxlq5e7xrnnjwbgr1401vqebn61ewewaasng45c.png\" alt=\"google@2x\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"2 von 5\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/hitech.al\/wp-content\/uploads\/elementor\/thumbs\/clutch-top1000-r9rmw1bu05skb1ttgsdeyea83a1mc770755601rqio.png\" alt=\"clutch top1000\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"3 von 5\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/hitech.al\/wp-content\/uploads\/elementor\/thumbs\/forbes2022-r9rmw29o6ztumnsgbas1iw1oonwzjwaqj9snhbqccg.png\" alt=\"forbes2022\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"4 von 5\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/hitech.al\/wp-content\/uploads\/elementor\/thumbs\/top_clutch-r9rmw0dztbr9zfv6m9ysdwirhw694i39v0hoirt4ow.png\" alt=\"top_clutch\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div><div class=\"swiper-slide\" role=\"group\" aria-roledescription=\"slide\" aria-label=\"5 von 5\"><figure class=\"swiper-slide-inner\"><img class=\"swiper-slide-image swiper-lazy\" data-src=\"https:\/\/hitech.al\/wp-content\/uploads\/elementor\/thumbs\/ny_nyc_managed-service-providers_2022_transparent-r9rmxlq5e7xrnnjwbgr1401vqebn61ewewaasng45c.png\" alt=\"ny_nyc_managed-service-providers_2022_transparent\" \/><div class=\"swiper-lazy-preloader\"><\/div><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5689527 elementor-section-items-stretch elementor-section-content-bottom elementor-section-height-min-height elementor-section-boxed elementor-section-height-default\" data-id=\"5689527\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5aba3de\" data-id=\"5aba3de\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-072b96a elementor-widget-mobile__width-inherit elementor-widget elementor-widget-heading\" data-id=\"072b96a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Gemeinsam besser<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c0cb50d elementor-widget-mobile__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"c0cb50d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir wissen, dass Arbeit wichtig ist, aber auch das Vergn\u00fcgen! Wir respektieren alle unsere Partnerschaften und bem\u00fchen uns, auf unterhaltsame Weise kritische Probleme zu l\u00f6sen und Ihnen gleichzeitig ein L\u00e4cheln ins Gesicht zu zaubern.<\/p><p>Wir lieben unseren Job und helfen unseren Kunden gerne. Das Leben ist einfach zu kurz, um nicht jede Minute zu genie\u00dfen!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"vamtam-has-theme-widget-styles elementor-element elementor-element-70e14dd elementor-widget__width-auto elementor-widget-mobile__width-inherit elementor-widget-tablet__width-auto elementor-widget elementor-widget-button\" data-id=\"70e14dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/hitech.al\/de\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Kontaktieren Sie uns<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-164a5ba\" data-id=\"164a5ba\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2ee8a5c elementor-widget elementor-widget-spacer\" data-id=\"2ee8a5c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Der Bereitstellung von Spitzenleistungen verpflichtet. Jeder hat eine Geschichte. Hier ist unsere. Der Anfang Unsere Reise begann 2013, als unser CEO Mandi Blaceri mit dem Aufbau einer E-Commerce-Website f\u00fcr das Familienunternehmen begann. Dies f\u00fchrte dazu, dass er sich intensiv mit der Web- und IT-Branche im Allgemeinen besch\u00e4ftigte. Mission Bei HiTech Media haben wir es uns zur Aufgabe gemacht, \u2026<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-85","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.7 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>About - HiTech Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/hitech.al\/de\/about\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About\" \/>\n<meta property=\"og:description\" content=\"Dedicated to delivering excellence Everyone has a story. Here is ours. The Begining Our journey began in 2013 when our CEO, Mandi Blaceri started building an e-commerce website for its family business. Which lead him to getting deep into Web and IT industry in general. Mission At HiTech Media, we\u2019re on a mission to bring...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/hitech.al\/de\/about\/\" \/>\n<meta property=\"og:site_name\" content=\"HiTech Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-12T14:16:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"566\" \/>\n\t<meta property=\"og:image:height\" content=\"428\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/hitech.al\\\/about\\\/\",\"url\":\"https:\\\/\\\/hitech.al\\\/about\\\/\",\"name\":\"About - HiTech Solutions\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/hitech.al\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/hitech.al\\\/about\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/hitech.al\\\/about\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/hitech.al\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg\",\"datePublished\":\"2023-03-09T12:53:47+00:00\",\"dateModified\":\"2025-08-12T14:16:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/hitech.al\\\/about\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/hitech.al\\\/about\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hitech.al\\\/about\\\/#primaryimage\",\"url\":\"https:\\\/\\\/hitech.al\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg\",\"contentUrl\":\"https:\\\/\\\/hitech.al\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/hitech.al\\\/about\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/hitech.al\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/hitech.al\\\/#website\",\"url\":\"https:\\\/\\\/hitech.al\\\/\",\"name\":\"HiTech Media\",\"description\":\"Your Digital Partner\",\"publisher\":{\"@id\":\"https:\\\/\\\/hitech.al\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/hitech.al\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/hitech.al\\\/#organization\",\"name\":\"HiTech Media\",\"url\":\"https:\\\/\\\/hitech.al\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/hitech.al\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/hitech.al\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HITech.png\",\"contentUrl\":\"https:\\\/\\\/hitech.al\\\/wp-content\\\/uploads\\\/2023\\\/03\\\/HITech.png\",\"width\":169,\"height\":40,\"caption\":\"HiTech Media\"},\"image\":{\"@id\":\"https:\\\/\\\/hitech.al\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u00dcber uns - HiTech-L\u00f6sungen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/hitech.al\/de\/about\/","og_locale":"de_DE","og_type":"article","og_title":"About","og_description":"Dedicated to delivering excellence Everyone has a story. Here is ours. The Begining Our journey began in 2013 when our CEO, Mandi Blaceri started building an e-commerce website for its family business. Which lead him to getting deep into Web and IT industry in general. Mission At HiTech Media, we\u2019re on a mission to bring...","og_url":"https:\/\/hitech.al\/de\/about\/","og_site_name":"HiTech Solutions","article_modified_time":"2025-08-12T14:16:24+00:00","og_image":[{"width":566,"height":428,"url":"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/hitech.al\/about\/","url":"https:\/\/hitech.al\/about\/","name":"\u00dcber uns - HiTech-L\u00f6sungen","isPartOf":{"@id":"https:\/\/hitech.al\/#website"},"primaryImageOfPage":{"@id":"https:\/\/hitech.al\/about\/#primaryimage"},"image":{"@id":"https:\/\/hitech.al\/about\/#primaryimage"},"thumbnailUrl":"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg","datePublished":"2023-03-09T12:53:47+00:00","dateModified":"2025-08-12T14:16:24+00:00","breadcrumb":{"@id":"https:\/\/hitech.al\/about\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/hitech.al\/about\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hitech.al\/about\/#primaryimage","url":"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg","contentUrl":"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/charlesdeluvio-Lks7vei-eAg-unsplash.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/hitech.al\/about\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/hitech.al\/"},{"@type":"ListItem","position":2,"name":"About"}]},{"@type":"WebSite","@id":"https:\/\/hitech.al\/#website","url":"https:\/\/hitech.al\/","name":"HiTech-Medien","description":"Ihr digitaler Partner","publisher":{"@id":"https:\/\/hitech.al\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/hitech.al\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/hitech.al\/#organization","name":"HiTech-Medien","url":"https:\/\/hitech.al\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/hitech.al\/#\/schema\/logo\/image\/","url":"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/HITech.png","contentUrl":"https:\/\/hitech.al\/wp-content\/uploads\/2023\/03\/HITech.png","width":169,"height":40,"caption":"HiTech Media"},"image":{"@id":"https:\/\/hitech.al\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/hitech.al\/de\/wp-json\/wp\/v2\/pages\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hitech.al\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/hitech.al\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/hitech.al\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hitech.al\/de\/wp-json\/wp\/v2\/comments?post=85"}],"version-history":[{"count":0,"href":"https:\/\/hitech.al\/de\/wp-json\/wp\/v2\/pages\/85\/revisions"}],"wp:attachment":[{"href":"https:\/\/hitech.al\/de\/wp-json\/wp\/v2\/media?parent=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}